{"id":1004,"date":"2023-09-11T01:59:47","date_gmt":"2023-09-11T01:59:47","guid":{"rendered":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/"},"modified":"2024-06-20T19:34:49","modified_gmt":"2024-06-20T19:34:49","slug":"super-truck-1000-mezclador","status":"publish","type":"product","link":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/","title":{"rendered":"SUPER TRUCK 1000 MEZCLADOR"},"content":{"rendered":"<p>Largo 20 cms x Ancho 13 cms x Alto 16 cms<br \/>\n64 UNDS<br \/>\nverde,rojo,azul,naranjado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Largo 20 cms x Ancho 13 cms x Alto 16 cms 64 UNDS verde,rojo,azul,naranjado<\/p>\n","protected":false},"featured_media":1253,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[21],"product_tag":[],"class_list":["post-1004","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-truck"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"og:description\" content=\"Largo 20 cms x Ancho 13 cms x Alto 16 cms 64 UNDS verde,rojo,azul,naranjado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T19:34:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/MEZCLADOR-TRUCK.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1270\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/\",\"name\":\"SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"isPartOf\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\"},\"datePublished\":\"2023-09-11T01:59:47+00:00\",\"dateModified\":\"2024-06-20T19:34:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUPER TRUCK 1000 MEZCLADOR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\",\"name\":\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"description\":\"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/","og_locale":"es_ES","og_type":"article","og_title":"SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","og_description":"Largo 20 cms x Ancho 13 cms x Alto 16 cms 64 UNDS verde,rojo,azul,naranjado","og_url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/","og_site_name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","article_modified_time":"2024-06-20T19:34:49+00:00","og_image":[{"width":1270,"height":1236,"url":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/MEZCLADOR-TRUCK.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/","url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/","name":"SUPER TRUCK 1000 MEZCLADOR - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","isPartOf":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website"},"datePublished":"2023-09-11T01:59:47+00:00","dateModified":"2024-06-20T19:34:49+00:00","breadcrumb":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/super-truck-1000-mezclador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyeccionesplasticas.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"SUPER TRUCK 1000 MEZCLADOR"}]},{"@type":"WebSite","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website","url":"https:\/\/proyeccionesplasticas.com.co\/web\/","name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","description":"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/comments?post=1004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media\/1253"}],"wp:attachment":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media?parent=1004"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_cat?post=1004"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_tag?post=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}