{"id":1580,"date":"2025-06-16T13:23:24","date_gmt":"2025-06-16T13:23:24","guid":{"rendered":"https:\/\/proyeccionesplasticas.com.co\/web\/?post_type=product&#038;p=1580"},"modified":"2025-06-16T13:25:05","modified_gmt":"2025-06-16T13:25:05","slug":"escurridor-cedazo-nature","status":"publish","type":"product","link":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/","title":{"rendered":"ESCURRIDOR CEDAZO NATURE"},"content":{"rendered":"<p>132 UNDS<br \/>\nLargo 28.5 cms x Ancho 17.5 cms x Alto 7.5 cms<br \/>\nbeige,verde pastel,gris pastel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>132 UNDS Largo 28.5 cms x Ancho 17.5 cms x Alto 7.5 cms beige,verde pastel,gris pastel<\/p>\n","protected":false},"featured_media":1581,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[22],"product_tag":[],"class_list":["post-1580","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"og:description\" content=\"132 UNDS Largo 28.5 cms x Ancho 17.5 cms x Alto 7.5 cms beige,verde pastel,gris pastel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T13:25:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2025\/06\/ESCURRIDOR-CEDAZO-NATURE.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1560\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/\",\"name\":\"ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"isPartOf\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\"},\"datePublished\":\"2025-06-16T13:23:24+00:00\",\"dateModified\":\"2025-06-16T13:25:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESCURRIDOR CEDAZO NATURE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\",\"name\":\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"description\":\"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/","og_locale":"es_ES","og_type":"article","og_title":"ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","og_description":"132 UNDS Largo 28.5 cms x Ancho 17.5 cms x Alto 7.5 cms beige,verde pastel,gris pastel","og_url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/","og_site_name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","article_modified_time":"2025-06-16T13:25:05+00:00","og_image":[{"width":1560,"height":994,"url":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2025\/06\/ESCURRIDOR-CEDAZO-NATURE.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/","url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/","name":"ESCURRIDOR CEDAZO NATURE - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","isPartOf":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website"},"datePublished":"2025-06-16T13:23:24+00:00","dateModified":"2025-06-16T13:25:05+00:00","breadcrumb":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/escurridor-cedazo-nature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyeccionesplasticas.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"ESCURRIDOR CEDAZO NATURE"}]},{"@type":"WebSite","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website","url":"https:\/\/proyeccionesplasticas.com.co\/web\/","name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","description":"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product\/1580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/comments?post=1580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media\/1581"}],"wp:attachment":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media?parent=1580"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_cat?post=1580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_tag?post=1580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}