{"id":712,"date":"2023-09-11T01:01:07","date_gmt":"2023-09-11T01:01:07","guid":{"rendered":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/"},"modified":"2023-09-11T01:01:20","modified_gmt":"2023-09-11T01:01:20","slug":"porta-vasos-x-6","status":"publish","type":"product","link":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/","title":{"rendered":"PORTA VASOS X 6"},"content":{"rendered":"<p>100 UNDS<br \/>\nDi\u00e1metro 9.5 cms x Alto 0.7 cms<br \/>\nazul,rojo,transparente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>100 UNDS Di\u00e1metro 9.5 cms x Alto 0.7 cms azul,rojo,transparente<\/p>\n","protected":false},"featured_media":713,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[22],"product_tag":[],"class_list":["post-712","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"og:description\" content=\"100 UNDS Di\u00e1metro 9.5 cms x Alto 0.7 cms azul,rojo,transparente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T01:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/portavasos-x-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/\",\"name\":\"PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"isPartOf\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\"},\"datePublished\":\"2023-09-11T01:01:07+00:00\",\"dateModified\":\"2023-09-11T01:01:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PORTA VASOS X 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\",\"name\":\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"description\":\"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/","og_locale":"es_ES","og_type":"article","og_title":"PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","og_description":"100 UNDS Di\u00e1metro 9.5 cms x Alto 0.7 cms azul,rojo,transparente","og_url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/","og_site_name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","article_modified_time":"2023-09-11T01:01:20+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/portavasos-x-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/","url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/","name":"PORTA VASOS X 6 - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","isPartOf":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website"},"datePublished":"2023-09-11T01:01:07+00:00","dateModified":"2023-09-11T01:01:20+00:00","breadcrumb":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/porta-vasos-x-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyeccionesplasticas.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"PORTA VASOS X 6"}]},{"@type":"WebSite","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website","url":"https:\/\/proyeccionesplasticas.com.co\/web\/","name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","description":"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product\/712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/comments?post=712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media\/713"}],"wp:attachment":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media?parent=712"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_cat?post=712"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_tag?post=712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}