{"id":786,"date":"2023-09-11T01:02:11","date_gmt":"2023-09-11T01:02:11","guid":{"rendered":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/"},"modified":"2026-05-11T16:58:53","modified_gmt":"2026-05-11T16:58:53","slug":"tarro-milusos-small-35-litros","status":"publish","type":"product","link":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/","title":{"rendered":"TARRO MILUSOS SMALL 3,5 LITROS"},"content":{"rendered":"<p>72 UNDS<br \/>\nDi\u00e1metro 23.4 cms x Alto 11.5 cms<br \/>\ncolor de tapa: rosado pastel,azul pastel,morado pastel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>72 UNDS Di\u00e1metro 23.4 cms x Alto 11.5 cms color de tapa: rosado pastel,azul pastel,morado pastel<\/p>\n","protected":false},"featured_media":1801,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[22],"product_tag":[],"class_list":["post-786","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"og:description\" content=\"72 UNDS Di\u00e1metro 23.4 cms x Alto 11.5 cms color de tapa: rosado pastel,azul pastel,morado pastel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T16:58:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/TARRO-MILUSOS-SMALL-3.5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1041\" \/>\n\t<meta property=\"og:image:height\" content=\"948\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/\",\"name\":\"TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"isPartOf\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\"},\"datePublished\":\"2023-09-11T01:02:11+00:00\",\"dateModified\":\"2026-05-11T16:58:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TARRO MILUSOS SMALL 3,5 LITROS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\",\"name\":\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"description\":\"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/","og_locale":"es_ES","og_type":"article","og_title":"TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","og_description":"72 UNDS Di\u00e1metro 23.4 cms x Alto 11.5 cms color de tapa: rosado pastel,azul pastel,morado pastel","og_url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/","og_site_name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","article_modified_time":"2026-05-11T16:58:53+00:00","og_image":[{"width":1041,"height":948,"url":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/TARRO-MILUSOS-SMALL-3.5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/","url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/","name":"TARRO MILUSOS SMALL 3,5 LITROS - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","isPartOf":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website"},"datePublished":"2023-09-11T01:02:11+00:00","dateModified":"2026-05-11T16:58:53+00:00","breadcrumb":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-small-35-litros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyeccionesplasticas.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"TARRO MILUSOS SMALL 3,5 LITROS"}]},{"@type":"WebSite","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website","url":"https:\/\/proyeccionesplasticas.com.co\/web\/","name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","description":"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product\/786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/comments?post=786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media\/1801"}],"wp:attachment":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media?parent=786"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_cat?post=786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_tag?post=786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}