{"id":810,"date":"2023-09-11T01:02:11","date_gmt":"2023-09-11T01:02:11","guid":{"rendered":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/"},"modified":"2025-03-10T13:09:40","modified_gmt":"2025-03-10T13:09:40","slug":"tarro-milusos-x-5-colores","status":"publish","type":"product","link":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/","title":{"rendered":"TARRO MILUSOS X 5 COLORES"},"content":{"rendered":"<p>22 UNDS<br \/>\n\u00bd ltrs : Di\u00e1metro 9.6 cms x Alto 10.1 cms 1 lts: Di\u00e1metro 10.5 cms x Alto 14.2 cms 2 lts: Di\u00e1metro 13.4 cms x Alto 17.1 cms 3.5 lts: Di\u00e1metro 18 cms x Alto 19.5 cms 5 lts : Di\u00e1metro 20.2 cms x Alto 21.8 cms<br \/>\ncolor de tapa:verde,naranjado,azul,rojo,negro,blanco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 UNDS \u00bd ltrs : Di\u00e1metro 9.6 cms x Alto 10.1 cms 1 lts: Di\u00e1metro 10.5 cms x Alto 14.2 cms 2 lts: Di\u00e1metro 13.4 cms x Alto 17.1 cms 3.5 lts: Di\u00e1metro 18 cms x Alto 19.5 cms 5 lts : Di\u00e1metro 20.2 cms x Alto 21.8 cms color de tapa:verde,naranjado,azul,rojo,negro,blanco<\/p>\n","protected":false},"featured_media":811,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[22],"product_tag":[],"class_list":["post-810","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-hogar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"og:description\" content=\"22 UNDS \u00bd ltrs : Di\u00e1metro 9.6 cms x Alto 10.1 cms 1 lts: Di\u00e1metro 10.5 cms x Alto 14.2 cms 2 lts: Di\u00e1metro 13.4 cms x Alto 17.1 cms 3.5 lts: Di\u00e1metro 18 cms x Alto 19.5 cms 5 lts : Di\u00e1metro 20.2 cms x Alto 21.8 cms color de tapa:verde,naranjado,azul,rojo,negro,blanco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-10T13:09:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/tarros-milusos-x-5-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/\",\"name\":\"TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"isPartOf\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\"},\"datePublished\":\"2023-09-11T01:02:11+00:00\",\"dateModified\":\"2025-03-10T13:09:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TARRO MILUSOS X 5 COLORES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/proyeccionesplasticas.com.co\/web\/#website\",\"url\":\"https:\/\/proyeccionesplasticas.com.co\/web\/\",\"name\":\"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999\",\"description\":\"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/","og_locale":"es_ES","og_type":"article","og_title":"TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","og_description":"22 UNDS \u00bd ltrs : Di\u00e1metro 9.6 cms x Alto 10.1 cms 1 lts: Di\u00e1metro 10.5 cms x Alto 14.2 cms 2 lts: Di\u00e1metro 13.4 cms x Alto 17.1 cms 3.5 lts: Di\u00e1metro 18 cms x Alto 19.5 cms 5 lts : Di\u00e1metro 20.2 cms x Alto 21.8 cms color de tapa:verde,naranjado,azul,rojo,negro,blanco","og_url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/","og_site_name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","article_modified_time":"2025-03-10T13:09:40+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-content\/uploads\/2023\/09\/tarros-milusos-x-5-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/","url":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/","name":"TARRO MILUSOS X 5 COLORES - Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","isPartOf":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website"},"datePublished":"2023-09-11T01:02:11+00:00","dateModified":"2025-03-10T13:09:40+00:00","breadcrumb":{"@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/producto\/tarro-milusos-x-5-colores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/proyeccionesplasticas.com.co\/web\/"},{"@type":"ListItem","position":2,"name":"TARRO MILUSOS X 5 COLORES"}]},{"@type":"WebSite","@id":"https:\/\/proyeccionesplasticas.com.co\/web\/#website","url":"https:\/\/proyeccionesplasticas.com.co\/web\/","name":"Proyecciones Pl&aacute;sticas S.A.S: Innovaci&oacute;n en Juguetes y Productos Educativos desde 1999","description":"Descubre c\u00f3mo Proyecciones Pl\u00e1sticas S.A.S, con m\u00e1s de dos d\u00e9cadas de experiencia, se ha convertido en un l\u00edder en la fabricaci\u00f3n de juguetes educativos y productos para el hogar. Nuestra pasi\u00f3n por la calidad y la innovaci\u00f3n nos ha llevado a la cima del mercado. \u00danete a nosotros y experimenta la diversi\u00f3n y el aprendizaje a trav\u00e9s de nuestros productos de alta calidad para grandes y chicos en todo el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyeccionesplasticas.com.co\/web\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product\/810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/comments?post=810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media\/811"}],"wp:attachment":[{"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/media?parent=810"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_cat?post=810"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/proyeccionesplasticas.com.co\/web\/wp-json\/wp\/v2\/product_tag?post=810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}